{"id":340,"date":"2017-12-01T04:23:57","date_gmt":"2017-12-01T04:23:57","guid":{"rendered":"https:\/\/www.sistemaimpulsa.com\/blog\/?p=340"},"modified":"2026-05-02T05:19:22","modified_gmt":"2026-05-02T05:19:22","slug":"keyword-palabra-clave","status":"publish","type":"post","link":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/","title":{"rendered":"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda"},"content":{"rendered":"<p style=\"text-align: justify;\">El <strong>SEO<\/strong> b\u00e1sicamente es ese proceso y conjunto de herramientas que utilizamos para conseguir una mejor posici\u00f3n en los <strong>motores de b\u00fasqueda<\/strong>. Comprende toda esa estructura de mec\u00e1nica y desaf\u00edo de competencia constante para colocar nuestro contenido de primero en esa popular lista de opciones que le dice al usuario que es lo que hay en la internet dependiendo de su b\u00fasqueda. La <strong>palabra clave<\/strong>, tambi\u00e9n conocida como <strong>Keyword<\/strong>, entra justo en esa organizaci\u00f3n como uno de los elementos m\u00e1s simples, pero a la vez importantes. Hoy definimos y te ense\u00f1amos su importancia de cara a tus <strong>estudios de marketing digital<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Concepto de palabra clave o Keyword<\/h2>\n<p style=\"text-align: justify;\">Una keyword es un <strong>conjunto de palabras<\/strong> que tienen la funci\u00f3n de ser un t\u00e9rmino de b\u00fasqueda creado por el usuario para ser utilizado en los motores de b\u00fasqueda que existen en la red <strong>para facilitar ese proceso de encontrar informaci\u00f3n directa<\/strong> y precisa sobre el inter\u00e9s que tenga la persona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-343\" src=\"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Keywords-o-palabras-clave.jpg\" alt=\"Keywords o palabras clave\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Keywords-o-palabras-clave.jpg 700w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Keywords-o-palabras-clave-300x169.jpg 300w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Keywords-o-palabras-clave-696x392.jpg 696w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Se podr\u00eda decir, que una keyword es una forma simplificada de hacer una b\u00fasqueda en internet. Para explicar mejor, <strong>un ejemplo pr\u00e1ctico<\/strong>:<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong><em>Leonardo necesita aprender a estudiar marketing digital. Su deseo es claro, quiere saber frente al buscador, cu\u00e1les son los institutos o universidades que se encargan de impartir las materias para tener un t\u00edtulo sobre el tema. Obviamente, Leo no va a colocar en el buscador todo su deseo, \u00e9l va a resumir todo eso a una palabra clave: Institutos Marketing Digital, tal vez, agregue la ciudad en la que vive, pero no m\u00e1s, porque se supone que el buscador entiende con \u00abpocas palabras\u00bb y nosotros con este conocimiento nos aprovechamos de esa \u00abinteligencia del buscador\u00bb<\/em><\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">C\u00f3mo sacar provecho de las palabras claves o keywords<\/h3>\n<p style=\"text-align: justify;\">Al entender que es una keyword, seguramente <strong>te habr\u00e1s dado cuenta de que en este contenido trabajamos con ellas<\/strong>. Hemos repetido mucho algunas palabras, pues tenemos una estructura jer\u00e1rquica con la que definimos las palabras claves en las que queremos participar luego de publicado el contenido en la red.<\/p>\n<p style=\"text-align: justify;\">Si nosotros no hici\u00e9ramos el trabajo como debemos y colocamos estas palabras claves al azar, no tendr\u00edamos la oportunidad que <strong>los robots de los motores de b\u00fasqueda<\/strong> nos encuentren y posicionen en las primeras p\u00e1ginas de las listas de b\u00fasqueda. Las keywords s\u00f3lo son el gancho directo para trabajar determinados contenidos y que de esta manera se muestren de primeros en las b\u00fasquedas, <strong>esto combinado con buena ortograf\u00eda<\/strong>, originalidad y un buen trabajo <strong><a href=\"\/blog\/tag\/seo\/\" target=\"_blank\" rel=\"noopener\">SEO<\/a><\/strong> del que m\u00e1s adelante hablaremos, garantiza la excelente posici\u00f3n que estamos tramando.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a1Comparte!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El SEO b\u00e1sicamente es ese proceso y conjunto de herramientas que utilizamos para conseguir una mejor posici\u00f3n en los motores de b\u00fasqueda. Comprende toda esa estructura de mec\u00e1nica y desaf\u00edo de competencia constante para colocar nuestro contenido de primero en esa popular lista de opciones que le dice al usuario que es lo que hay [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":344,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,2914],"tags":[42,41],"class_list":["post-340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital","category-funnel-tofu","tag-motores-de-busqueda","tag-seo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda - Impulsa blog<\/title>\n<meta name=\"description\" content=\"La Keyword o Palabra clave es uno de los instrumentos mas elementales del trabajo SEO que debes hacer a tu proyecto de marketing digital en esta era...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda - Impulsa blog\" \/>\n<meta property=\"og:description\" content=\"La Keyword o Palabra clave es uno de los instrumentos mas elementales del trabajo SEO que debes hacer a tu proyecto de marketing digital en esta era...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Ventas y Digitalizaci\u00f3n - Impulsa\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-01T04:23:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T05:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Que-son-keywords-o-palabras-claves.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/\"},\"author\":{\"name\":\"Leonardo\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#\\\/schema\\\/person\\\/87308861dcb5a84a45be5bd57dc94521\"},\"headline\":\"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda\",\"datePublished\":\"2017-12-01T04:23:57+00:00\",\"dateModified\":\"2026-05-02T05:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/\"},\"wordCount\":467,\"image\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Que-son-keywords-o-palabras-claves.jpg\",\"keywords\":[\"motores de busqueda\",\"SEO\"],\"articleSection\":[\"Marketing Digital\",\"TOFU\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/\",\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/\",\"name\":\"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda - Impulsa blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Que-son-keywords-o-palabras-claves.jpg\",\"datePublished\":\"2017-12-01T04:23:57+00:00\",\"dateModified\":\"2026-05-02T05:19:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#\\\/schema\\\/person\\\/87308861dcb5a84a45be5bd57dc94521\"},\"description\":\"La Keyword o Palabra clave es uno de los instrumentos mas elementales del trabajo SEO que debes hacer a tu proyecto de marketing digital en esta era...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Que-son-keywords-o-palabras-claves.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Que-son-keywords-o-palabras-claves.jpg\",\"width\":700,\"height\":394,\"caption\":\"Que son keywords o palabras claves\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/keyword-palabra-clave\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/\",\"name\":\"Blog de Ventas y Digitalizaci\u00f3n - Impulsa\",\"description\":\"Blog dedicado a ayudar a emprendedores, pymes y empresas sobre ventas y digitalizaci\u00f3n, explicando en simple los contenidos complejos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#\\\/schema\\\/person\\\/87308861dcb5a84a45be5bd57dc94521\",\"name\":\"Leonardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fb4688f9c1c298508c476bb7eefd7c31584ef941c9aff79035f33abfa59b90e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fb4688f9c1c298508c476bb7eefd7c31584ef941c9aff79035f33abfa59b90e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fb4688f9c1c298508c476bb7eefd7c31584ef941c9aff79035f33abfa59b90e?s=96&d=mm&r=g\",\"caption\":\"Leonardo\"},\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/author\\\/leonardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda - Impulsa blog","description":"La Keyword o Palabra clave es uno de los instrumentos mas elementales del trabajo SEO que debes hacer a tu proyecto de marketing digital en esta era...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/","og_locale":"es_ES","og_type":"article","og_title":"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda - Impulsa blog","og_description":"La Keyword o Palabra clave es uno de los instrumentos mas elementales del trabajo SEO que debes hacer a tu proyecto de marketing digital en esta era...","og_url":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/","og_site_name":"Blog de Ventas y Digitalizaci\u00f3n - Impulsa","article_published_time":"2017-12-01T04:23:57+00:00","article_modified_time":"2026-05-02T05:19:22+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Que-son-keywords-o-palabras-claves.jpg","type":"image\/jpeg"}],"author":"Leonardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#article","isPartOf":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/"},"author":{"name":"Leonardo","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#\/schema\/person\/87308861dcb5a84a45be5bd57dc94521"},"headline":"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda","datePublished":"2017-12-01T04:23:57+00:00","dateModified":"2026-05-02T05:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/"},"wordCount":467,"image":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Que-son-keywords-o-palabras-claves.jpg","keywords":["motores de busqueda","SEO"],"articleSection":["Marketing Digital","TOFU"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/","url":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/","name":"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda - Impulsa blog","isPartOf":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#primaryimage"},"image":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Que-son-keywords-o-palabras-claves.jpg","datePublished":"2017-12-01T04:23:57+00:00","dateModified":"2026-05-02T05:19:22+00:00","author":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#\/schema\/person\/87308861dcb5a84a45be5bd57dc94521"},"description":"La Keyword o Palabra clave es uno de los instrumentos mas elementales del trabajo SEO que debes hacer a tu proyecto de marketing digital en esta era...","breadcrumb":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#primaryimage","url":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Que-son-keywords-o-palabras-claves.jpg","contentUrl":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2017\/12\/Que-son-keywords-o-palabras-claves.jpg","width":700,"height":394,"caption":"Que son keywords o palabras claves"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/keyword-palabra-clave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sistemaimpulsa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Keyword o Palabra Clave: El poder de los motores de b\u00fasqueda"}]},{"@type":"WebSite","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#website","url":"https:\/\/www.sistemaimpulsa.com\/blog\/","name":"Blog de Ventas y Digitalizaci\u00f3n - Impulsa","description":"Blog dedicado a ayudar a emprendedores, pymes y empresas sobre ventas y digitalizaci\u00f3n, explicando en simple los contenidos complejos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sistemaimpulsa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#\/schema\/person\/87308861dcb5a84a45be5bd57dc94521","name":"Leonardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6fb4688f9c1c298508c476bb7eefd7c31584ef941c9aff79035f33abfa59b90e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fb4688f9c1c298508c476bb7eefd7c31584ef941c9aff79035f33abfa59b90e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fb4688f9c1c298508c476bb7eefd7c31584ef941c9aff79035f33abfa59b90e?s=96&d=mm&r=g","caption":"Leonardo"},"url":"https:\/\/www.sistemaimpulsa.com\/blog\/author\/leonardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts\/340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/comments?post=340"}],"version-history":[{"count":6,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts\/340\/revisions"}],"predecessor-version":[{"id":347,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts\/340\/revisions\/347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/media\/344"}],"wp:attachment":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/media?parent=340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/categories?post=340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/tags?post=340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}