{"id":5447,"date":"2020-02-26T12:06:23","date_gmt":"2020-02-26T12:06:23","guid":{"rendered":"https:\/\/www.sistemaimpulsa.com\/blog\/?p=5447"},"modified":"2026-05-02T02:16:03","modified_gmt":"2026-05-02T02:16:03","slug":"como-puede-tu-empresa-contribuir-con-el-medio-ambiente","status":"publish","type":"post","link":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/","title":{"rendered":"C\u00f3mo puede tu empresa contribuir con el medio ambiente"},"content":{"rendered":"<p>\u00bfTienes una empresa y deseas <strong>contribuir con el medio ambiente<\/strong>? Hoy d\u00eda son m\u00e1s las empresas que se suman a esta causa ecol\u00f3gica para el cuidado de nuestro planeta tierra, tu empresa tambi\u00e9n puede ser una de estas. Existen diferentes facetas en donde puede participar o contribuir una empresa, a continuaci\u00f3n, mencionaremos algunas.<\/p>\n<p><b>Ayuda al medio ambiente desde tu empresa<\/b><\/p>\n<p>Existen actividades para ayudar al medioambiente desde casa y otras para hacerlo desde las empresas; pueden ser actividades programadas desde instituciones que est\u00e1n enfocadas al cuidado del planeta y las empresas como tal puede tomar la iniciativa en realizar cambios que logren <strong>contribuir con el medio ambiente.<\/strong><\/p>\n<p>Las gestiones para reducir el impacto ambiental pueden hacerlas cualquier empresa sin importar el sector en el que trabaje; <strong>solo deben establecer medidas claras y llevarlas a cabo<\/strong>. Necesitar\u00e1s explicar por qu\u00e9 la empresa sufrir\u00e1 algunos cambios internos y c\u00f3mo ayuda eso al medio ambiente, de esta forma todo el personal se ver\u00e1 involucrado y participar\u00e1 en las actividades propuestas.<\/p>\n<h2>\u00bfC\u00f3mo contribuir con el medio ambiente desde tu\u00a0 empresa?<\/h2>\n<p>Se puede ver como cierto n\u00famero de empresas desde hace un tiempo, han adoptado un enfoque verde para contribuir con el medio ambiente; algunas prefieren adaptarse a las normas relacionadas con el medioambiente para evitar sanciones en cualquier actividad que realicen.<\/p>\n<p>Aunque no est\u00e1 mal solo basarse en las normas existentes, pueden las empresas ir m\u00e1s all\u00e1 de estas y ayudar a\u00fan m\u00e1s al planeta tierra; si hacen esto pueden fortalecer y hacer crecer la cultura de las empresas responsables. Lo ideal es crear conciencia en todos sus trabajadores y que participen en cada una de las actividades programadas.<\/p>\n<h3>Ideas para el ahorro energ\u00e9tico<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5449 aligncenter\" src=\"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22.jpg\" alt=\"\" width=\"531\" height=\"347\" srcset=\"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22.jpg 1200w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-300x196.jpg 300w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-1024x669.jpg 1024w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-768x502.jpg 768w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-696x455.jpg 696w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-741x486.jpg 741w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-1068x698.jpg 1068w, https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/2-22-643x420.jpg 643w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/p>\n<p>Entre las medidas m\u00e1s destacadas que se encuentran en el ahorro energ\u00e9tico se pueden realizar actividades como:<\/p>\n<ul>\n<li>Cambios de equipo de iluminaci\u00f3n y climatizaci\u00f3n<\/li>\n<\/ul>\n<p>Se puede realizar <strong>cambios de bombillos, desconexi\u00f3n de los equipos electr\u00f3nicos<\/strong> cuando no son usados; hoy d\u00eda se puede sacar provecho de la tecnolog\u00eda led para mejorar la eficiencia energ\u00e9tica para el cuidado del medioambiente.<\/p>\n<ul>\n<li>Reciclaje<\/li>\n<\/ul>\n<p>Toda empresa posee y genera residuos o desperdicios que pueden ser reciclados; por ejemplo, el reciclaje de pl\u00e1stico y papel. En estos casos pueden identificarse distintos recipientes en donde desechar el pl\u00e1stico de manera correcta y seleccionada.<\/p>\n<p>Con el papel pueden ser reutilizadas las hojas que tienen una cara libre, tambi\u00e9n se puede desechar las hojas en recipientes identificados para una mejor selecci\u00f3n a la hora de reciclar. Adem\u00e1s, el <strong>reemplazar el papel por formatos digitales<\/strong> crea un impacto positivo al medio ambiente.<\/p>\n<ul>\n<li>Dile s\u00ed a las oficinas verdes<\/li>\n<\/ul>\n<p>Si vas construir un edificio desde cero puedes dise\u00f1ar espacios que sean bioclim\u00e1ticos; adem\u00e1s se pueden utilizar materiales renovados y reciclables. La arquitectura bioclim\u00e1tica es una rama que toma la iniciativa en dise\u00f1os donde se saque provecho a la luz solar y la climatizaci\u00f3n natural.<\/p>\n<h2>Reducci\u00f3n de impacto<\/h2>\n<p>Debemos reducir cualquier impacto que la empresa pueda generar hacia el medio ambiente; algunas empresas fomentan el uso de bicicletas en vez de veh\u00edculos, tambi\u00e9n el uso de materia prima y recursos que sean de menor impacto al planeta tierra.<\/p>\n<p>La reducci\u00f3n de impacto, actividades que mejoren el ahorro de energ\u00eda, entre otras pueden incluirlas las empresas. Adem\u00e1s, toda empresa debe mantener un programa de actividades y de dise\u00f1os que logren <strong>contribuir con el medio ambiente.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTienes una empresa y deseas contribuir con el medio ambiente? Hoy d\u00eda son m\u00e1s las empresas que se suman a esta causa ecol\u00f3gica para el cuidado de nuestro planeta tierra, tu empresa tambi\u00e9n puede ser una de estas. Existen diferentes facetas en donde puede participar o contribuir una empresa, a continuaci\u00f3n, mencionaremos algunas. Ayuda al [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":5448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,2914],"tags":[1017,160,281,1016],"class_list":["post-5447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital","category-funnel-tofu","tag-conciencia","tag-empleados","tag-empresa","tag-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo puede tu empresa contribuir con el medio ambiente - Impulsa blog<\/title>\n<meta name=\"description\" content=\"Las empresas pueden contribuir en mejorar el medio ambiente,implementando para ello de actividades que fomenten conciencia hacia nuestro planeta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo puede tu empresa contribuir con el medio ambiente - Impulsa blog\" \/>\n<meta property=\"og:description\" content=\"Las empresas pueden contribuir en mejorar el medio ambiente,implementando para ello de actividades que fomenten conciencia hacia nuestro planeta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Ventas y Digitalizaci\u00f3n - Impulsa\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-26T12:06:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T02:16:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/1-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jesus P.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jesus P.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/\"},\"author\":{\"name\":\"Jesus P.\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#\\\/schema\\\/person\\\/9b776e2045dc9a9212dea4b32163f07d\"},\"headline\":\"C\u00f3mo puede tu empresa contribuir con el medio ambiente\",\"datePublished\":\"2020-02-26T12:06:23+00:00\",\"dateModified\":\"2026-05-02T02:16:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/\"},\"wordCount\":604,\"image\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1-24.jpg\",\"keywords\":[\"conciencia\",\"empleados\",\"empresa\",\"medio ambiente\"],\"articleSection\":[\"Marketing Digital\",\"TOFU\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/\",\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/\",\"name\":\"C\u00f3mo puede tu empresa contribuir con el medio ambiente - Impulsa blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1-24.jpg\",\"datePublished\":\"2020-02-26T12:06:23+00:00\",\"dateModified\":\"2026-05-02T02:16:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#\\\/schema\\\/person\\\/9b776e2045dc9a9212dea4b32163f07d\"},\"description\":\"Las empresas pueden contribuir en mejorar el medio ambiente,implementando para ello de actividades que fomenten conciencia hacia nuestro planeta\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1-24.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1-24.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo puede tu empresa contribuir con el medio ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/\",\"name\":\"Blog de Ventas y Digitalizaci\u00f3n - Impulsa\",\"description\":\"Blog dedicado a ayudar a emprendedores, pymes y empresas sobre ventas y digitalizaci\u00f3n, explicando en simple los contenidos complejos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/#\\\/schema\\\/person\\\/9b776e2045dc9a9212dea4b32163f07d\",\"name\":\"Jesus P.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39142e6ba7f19ca961abe851a818b268a41e284a62ca332a054cb338164ff61f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39142e6ba7f19ca961abe851a818b268a41e284a62ca332a054cb338164ff61f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39142e6ba7f19ca961abe851a818b268a41e284a62ca332a054cb338164ff61f?s=96&d=mm&r=g\",\"caption\":\"Jesus P.\"},\"url\":\"https:\\\/\\\/www.sistemaimpulsa.com\\\/blog\\\/author\\\/comoemprender-netgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo puede tu empresa contribuir con el medio ambiente - Impulsa blog","description":"Las empresas pueden contribuir en mejorar el medio ambiente,implementando para ello de actividades que fomenten conciencia hacia nuestro planeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo puede tu empresa contribuir con el medio ambiente - Impulsa blog","og_description":"Las empresas pueden contribuir en mejorar el medio ambiente,implementando para ello de actividades que fomenten conciencia hacia nuestro planeta","og_url":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/","og_site_name":"Blog de Ventas y Digitalizaci\u00f3n - Impulsa","article_published_time":"2020-02-26T12:06:23+00:00","article_modified_time":"2026-05-02T02:16:03+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/1-24.jpg","type":"image\/jpeg"}],"author":"Jesus P.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jesus P.","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#article","isPartOf":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/"},"author":{"name":"Jesus P.","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#\/schema\/person\/9b776e2045dc9a9212dea4b32163f07d"},"headline":"C\u00f3mo puede tu empresa contribuir con el medio ambiente","datePublished":"2020-02-26T12:06:23+00:00","dateModified":"2026-05-02T02:16:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/"},"wordCount":604,"image":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/1-24.jpg","keywords":["conciencia","empleados","empresa","medio ambiente"],"articleSection":["Marketing Digital","TOFU"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/","url":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/","name":"C\u00f3mo puede tu empresa contribuir con el medio ambiente - Impulsa blog","isPartOf":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/1-24.jpg","datePublished":"2020-02-26T12:06:23+00:00","dateModified":"2026-05-02T02:16:03+00:00","author":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#\/schema\/person\/9b776e2045dc9a9212dea4b32163f07d"},"description":"Las empresas pueden contribuir en mejorar el medio ambiente,implementando para ello de actividades que fomenten conciencia hacia nuestro planeta","breadcrumb":{"@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#primaryimage","url":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/1-24.jpg","contentUrl":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-content\/uploads\/2020\/02\/1-24.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/como-puede-tu-empresa-contribuir-con-el-medio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sistemaimpulsa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo puede tu empresa contribuir con el medio ambiente"}]},{"@type":"WebSite","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#website","url":"https:\/\/www.sistemaimpulsa.com\/blog\/","name":"Blog de Ventas y Digitalizaci\u00f3n - Impulsa","description":"Blog dedicado a ayudar a emprendedores, pymes y empresas sobre ventas y digitalizaci\u00f3n, explicando en simple los contenidos complejos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sistemaimpulsa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.sistemaimpulsa.com\/blog\/#\/schema\/person\/9b776e2045dc9a9212dea4b32163f07d","name":"Jesus P.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/39142e6ba7f19ca961abe851a818b268a41e284a62ca332a054cb338164ff61f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39142e6ba7f19ca961abe851a818b268a41e284a62ca332a054cb338164ff61f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39142e6ba7f19ca961abe851a818b268a41e284a62ca332a054cb338164ff61f?s=96&d=mm&r=g","caption":"Jesus P."},"url":"https:\/\/www.sistemaimpulsa.com\/blog\/author\/comoemprender-netgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts\/5447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/comments?post=5447"}],"version-history":[{"count":1,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts\/5447\/revisions"}],"predecessor-version":[{"id":5450,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/posts\/5447\/revisions\/5450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/media\/5448"}],"wp:attachment":[{"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/media?parent=5447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/categories?post=5447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sistemaimpulsa.com\/blog\/wp-json\/wp\/v2\/tags?post=5447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}